{"id":551,"count":1,"description":"","link":"https:\/\/www.erde-in-bildern.de\/reiseblog\/tag\/oberhausen\/","name":"Oberhausen","slug":"oberhausen","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.erde-in-bildern.de\/reiseblog\/wp-json\/wp\/v2\/tags\/551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erde-in-bildern.de\/reiseblog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.erde-in-bildern.de\/reiseblog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.erde-in-bildern.de\/reiseblog\/wp-json\/wp\/v2\/posts?tags=551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}